{"id":1764,"date":"2025-12-03T12:36:13","date_gmt":"2025-12-03T12:36:13","guid":{"rendered":"https:\/\/bookbuddy.snapplify.ai\/za\/product\/isindebele-ilimi-lekhaya-iphepha-lesibili-igreyidi-12-novemba-2024-umhlahlandlela-wokutshwaya\/"},"modified":"2025-12-04T15:10:33","modified_gmt":"2025-12-04T15:10:33","slug":"isindebele-ilimi-lekhaya-iphepha-lesibili-igreyidi-12-novemba-2024-umhlahlandlela-wokutshwaya","status":"publish","type":"product","link":"https:\/\/bookbuddy.snapplify.ai\/za\/product\/isindebele-ilimi-lekhaya-iphepha-lesibili-igreyidi-12-novemba-2024-umhlahlandlela-wokutshwaya\/","title":{"rendered":"Isindebele Ilimi Lekhaya Iphepha Lesibili Igreyidi 12 Novemba 2024 Umhlahlandlela Wokutshwaya"},"content":{"rendered":"<p>Le ngxenye yokuhlola ijolise ekulinganiseni amakhono abafundi ngokwazisa imibhalo eyahlukenekufaka phakathi iinkondlo, novela (iindaba ezinde), nama-drama (imidlalo).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ngxenye yokuhlola ijolise ekulinganiseni amakhono abafundi ngokwazisa imibhalo eyahlukenekufaka phakathi iinkondlo, novela (iindaba ezinde), nama-drama (imidlalo).<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":{"0":"post-1764","1":"product","2":"type-product","3":"status-publish","5":"product_cat-exam-papers","6":"pa_copyright-rsa-depart-of-education","7":"pa_language-ndebele-south-south-ndebele","8":"pa_publisher-rsa-depart-of-education","10":"first","11":"instock","12":"virtual","13":"sold-individually","14":"taxable","15":"purchasable","16":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/bookbuddy.snapplify.ai\/za\/wp-json\/wp\/v2\/product\/1764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bookbuddy.snapplify.ai\/za\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bookbuddy.snapplify.ai\/za\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/bookbuddy.snapplify.ai\/za\/wp-json\/wp\/v2\/media?parent=1764"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bookbuddy.snapplify.ai\/za\/wp-json\/wp\/v2\/product_brand?post=1764"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bookbuddy.snapplify.ai\/za\/wp-json\/wp\/v2\/product_cat?post=1764"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bookbuddy.snapplify.ai\/za\/wp-json\/wp\/v2\/product_tag?post=1764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}